{"id":2035,"date":"2023-11-24T20:17:19","date_gmt":"2023-11-24T20:17:19","guid":{"rendered":"https:\/\/www.cedixperu.com\/?page_id=2035"},"modified":"2023-11-25T11:40:48","modified_gmt":"2023-11-25T11:40:48","slug":"radiografia-periapical-rvg1","status":"publish","type":"page","link":"https:\/\/www.cedixperu.com\/web\/radiografia-periapical-rvg1\/","title":{"rendered":"Radiograf\u00eda Periapical RVG1"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb global_module=\u00bb2136&#8243; theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb0px||0px||false|false\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_divider show_divider=\u00bboff\u00bb _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/et_pb_divider][et_pb_heading title=\u00bbSERVICIOS\u00bb _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bbRubik|600|||||||\u00bb title_text_align=\u00bbcenter\u00bb background_color=\u00bb#e8e8e8&#8243; custom_padding=\u00bb10px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/et_pb_heading][\/et_pb_column][\/et_pb_row][et_pb_row use_custom_gutter=\u00bbon\u00bb _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbRGBA(255,255,255,0)\u00bb custom_margin=\u00bb0px||0px||false|false\u00bb custom_padding=\u00bb5px||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_heading title=\u00bbRadiograf\u00eda Periapical\u00bb _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bbRubik|600|||||||\u00bb title_text_align=\u00bbcenter\u00bb title_text_color=\u00bb#FFFFFF\u00bb title_font_size=\u00bb24px\u00bb background_color=\u00bb#76b729&#8243; custom_padding=\u00bb10px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/et_pb_heading][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb2&#8243; make_equal=\u00bbon\u00bb _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbRGBA(255,255,255,0)\u00bb custom_css_main_element=\u00bbmargin:auto;\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbRGBA(255,255,255,0)\u00bb custom_padding=\u00bb15px||15px|15px|true|false\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p>Las radiograf\u00edas complementan la evaluaci\u00f3n cl\u00ednica que se puede realizar a un paciente, permite complementar un diagn\u00f3stico inicial y de este modo, planificar un tratamiento individualizado a cada paciente.<\/p>\n<p><strong>Ventajas:<\/strong><\/p>\n<p><strong>Menor Radiaci\u00f3n:<\/strong> La posibilidad de ajustar digitalmente la imagen nos permite dar menor radiaci\u00f3n al paciente y corregir errores de exposici\u00f3n.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_gallery gallery_ids=\u00bb2133,2134&#8243; fullwidth=\u00bbon\u00bb _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb auto=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_divider show_divider=\u00bboff\u00bb _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las radiograf\u00edas complementan la evaluaci\u00f3n cl\u00ednica que se puede realizar a un paciente, permite complementar un diagn\u00f3stico inicial y de este modo, planificar un tratamiento individualizado a cada paciente. Ventajas: Menor Radiaci\u00f3n: La posibilidad de ajustar digitalmente la imagen nos permite dar menor radiaci\u00f3n al paciente y corregir errores de exposici\u00f3n.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-2035","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.cedixperu.com\/web\/wp-json\/wp\/v2\/pages\/2035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cedixperu.com\/web\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cedixperu.com\/web\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cedixperu.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cedixperu.com\/web\/wp-json\/wp\/v2\/comments?post=2035"}],"version-history":[{"count":3,"href":"https:\/\/www.cedixperu.com\/web\/wp-json\/wp\/v2\/pages\/2035\/revisions"}],"predecessor-version":[{"id":2139,"href":"https:\/\/www.cedixperu.com\/web\/wp-json\/wp\/v2\/pages\/2035\/revisions\/2139"}],"wp:attachment":[{"href":"https:\/\/www.cedixperu.com\/web\/wp-json\/wp\/v2\/media?parent=2035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}